{"id":2188,"date":"2018-11-21T14:32:30","date_gmt":"2018-11-21T13:32:30","guid":{"rendered":"https:\/\/grenzinfo.eu\/erw\/?p=2188"},"modified":"2018-11-21T14:32:30","modified_gmt":"2018-11-21T13:32:30","slug":"business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt","status":"publish","type":"post","link":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/","title":{"rendered":"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt"},"content":{"rendered":"<p>\t\t\t\t<strong>Klever Unternehmen \u00e4u\u00dfern unter anderem aufgrund der nachhaltig guten Konjunktur einen steigenden Fachkr\u00e4ftebedarf. Dieser kann jedoch nicht immer zeitnah und fachlich passend gedeckt werden. Deshalb organisiert die Wirtschaft &amp; Tourismus Stadt Kleve GmbH das n\u00e4chste Business-Fr\u00fchst\u00fcck am Freitag, 30. November, in der Stadthalle Kleve in Zusammenarbeit mit dem in Kleve ans\u00e4ssigen GrenzInfoPunkt der Euregio Rhein-Waal. Bei der Veranstaltung zum Thema \u201eWie erschlie\u00dfe ich den grenz\u00fcberschreitenden Arbeitsmarkt?\u201c erhalten die Unternehmer konkrete Tipps.<\/strong><\/p>\n<p>F\u00fcr Unternehmer in Kleve kann es verschiedene Gr\u00fcnde geben, sich mit dem deutsch-niederl\u00e4ndischen Arbeitsmarkt auseinanderzusetzen. Ein Stichpunkt ist das Thema Fachkr\u00e4ftemangel \u2013 hier lohnt ein Blick ins Nachbarland, um neues Personal zu werben. Wer bereits im Nachbarland aktiv ist oder es sein m\u00f6chte, ist gut beraten, Personal auf dem niederl\u00e4ndischen Arbeitsmarkt zu suchen. Unternehmen, die bereits Personal aus dem Nachbarland besch\u00e4ftigen, sorgen sich wom\u00f6glich darum, wie sie es langfristig halten k\u00f6nnen.<\/p>\n<p>Dabei tauchen verschiedene Fragen auf: Was gibt es zu beachten, wenn ich Niederl\u00e4nder besch\u00e4ftige? Und wieso schicken Niederl\u00e4nder, wenn sie sich bewerben, fast nie Zeugnisse mit? Auf diese und weitere Aspekte gehen unter anderem die Experten vom GrenzInfoPunkt der Euregio Rhein-Waal an diesem Morgen ein. Der GrenzInfoPunkt Rhein-Waal ist eine grenz\u00fcberschreitende Partnerschaft mehrerer Organisationen. Jeder Partner stellt sein spezielles Wissen zur Verf\u00fcgung. Auf dieser Grundlage beraten sie gemeinsam zu den Themen Wohnen, Arbeiten, Gesch\u00e4ftswelt und Studieren im Nachbarland.<\/p>\n<p><strong>Programm<\/strong><\/p>\n<p>Nach der offiziellen Begr\u00fc\u00dfung und dem aktuellen Bericht zur st\u00e4dtischen Haushaltsplanung 2019 beginnen Stefanie R\u00f6sing und Michael Stock vom Arbeitgeberservice des UWV Doetinchem mit einem Vortrag zum Thema Arbeitsvermittlung aus den Niederlanden. Als EURES Cross-Border Berater betreuen sie die Arbeitgeber in den Regionen Achterhoek, Arnheim und Nimwegen und auch im deutschen Grenzgebiet.<\/p>\n<p>Bei der folgenden Podiumsdiskussion er\u00f6rtert Frank W\u00f6bbeking, Gesch\u00e4ftsf\u00fchrer der deutsch-niederl\u00e4ndischen Kommunikationsagentur mediamixx GmbH aus Kleve, im Gespr\u00e4ch mit Wilfried Kullmann, Teamleiter des Arbeitgeberservice der Agentur f\u00fcr Arbeit Wesel f\u00fcr den Kreis Kleve und Line Manager EURES, und Daniel Jaetsch, Consultant und Personalvermittler bei Velde Groep in Den Bosch, einige konkrete Fragen zum grenz\u00fcberschreitenden Arbeitsmarkt.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Foto: Daniel Jaetsch<\/em>\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Klever Unternehmen \u00e4u\u00dfern unter anderem aufgrund der nachhaltig guten Konjunktur einen steigenden Fachkr\u00e4ftebedarf. Dieser kann jedoch nicht immer zeitnah und fachlich passend gedeckt werden. Deshalb organisiert die Wirtschaft &amp; Tourismus Stadt Kleve GmbH das n\u00e4chste Business-Fr\u00fchst\u00fcck am Freitag, 30. November, in der Stadthalle Kleve in Zusammenarbeit mit dem in Kleve ans\u00e4ssigen GrenzInfoPunkt der Euregio Rhein-Waal. [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":2189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt - Rhein-Waal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt - Rhein-Waal\" \/>\n<meta property=\"og:description\" content=\"Klever Unternehmen \u00e4u\u00dfern unter anderem aufgrund der nachhaltig guten Konjunktur einen steigenden Fachkr\u00e4ftebedarf. Dieser kann jedoch nicht immer zeitnah und fachlich passend gedeckt werden. Deshalb organisiert die Wirtschaft &amp; Tourismus Stadt Kleve GmbH das n\u00e4chste Business-Fr\u00fchst\u00fcck am Freitag, 30. November, in der Stadthalle Kleve in Zusammenarbeit mit dem in Kleve ans\u00e4ssigen GrenzInfoPunkt der Euregio Rhein-Waal. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/\" \/>\n<meta property=\"og:site_name\" content=\"Rhein-Waal\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-21T13:32:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grenzinfo.eu\/erw\/wp-content\/uploads\/sites\/7\/2018\/11\/Jaetsch-Daniel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"flipse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"flipse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/\"},\"author\":{\"name\":\"flipse\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/#\\\/schema\\\/person\\\/ec7710b37fdb52b8fb42d84b368d705f\"},\"headline\":\"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt\",\"datePublished\":\"2018-11-21T13:32:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/\"},\"wordCount\":371,\"image\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/Jaetsch-Daniel.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/\",\"url\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/\",\"name\":\"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt - Rhein-Waal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/Jaetsch-Daniel.jpg\",\"datePublished\":\"2018-11-21T13:32:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/#\\\/schema\\\/person\\\/ec7710b37fdb52b8fb42d84b368d705f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/Jaetsch-Daniel.jpg\",\"contentUrl\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/11\\\/Jaetsch-Daniel.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/nl\\\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/#website\",\"url\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/\",\"name\":\"Rhein-Waal\",\"description\":\"Grenzinfopunkt Rhein-Waal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/#\\\/schema\\\/person\\\/ec7710b37fdb52b8fb42d84b368d705f\",\"name\":\"flipse\",\"url\":\"https:\\\/\\\/grenzinfo.eu\\\/erw\\\/author\\\/flipse\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt - Rhein-Waal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/","og_locale":"de_DE","og_type":"article","og_title":"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt - Rhein-Waal","og_description":"Klever Unternehmen \u00e4u\u00dfern unter anderem aufgrund der nachhaltig guten Konjunktur einen steigenden Fachkr\u00e4ftebedarf. Dieser kann jedoch nicht immer zeitnah und fachlich passend gedeckt werden. Deshalb organisiert die Wirtschaft &amp; Tourismus Stadt Kleve GmbH das n\u00e4chste Business-Fr\u00fchst\u00fcck am Freitag, 30. November, in der Stadthalle Kleve in Zusammenarbeit mit dem in Kleve ans\u00e4ssigen GrenzInfoPunkt der Euregio Rhein-Waal. [&hellip;]","og_url":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/","og_site_name":"Rhein-Waal","article_published_time":"2018-11-21T13:32:30+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/grenzinfo.eu\/erw\/wp-content\/uploads\/sites\/7\/2018\/11\/Jaetsch-Daniel.jpg","type":"image\/jpeg"}],"author":"flipse","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"flipse","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#article","isPartOf":{"@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/"},"author":{"name":"flipse","@id":"https:\/\/grenzinfo.eu\/erw\/#\/schema\/person\/ec7710b37fdb52b8fb42d84b368d705f"},"headline":"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt","datePublished":"2018-11-21T13:32:30+00:00","mainEntityOfPage":{"@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/"},"wordCount":371,"image":{"@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#primaryimage"},"thumbnailUrl":"https:\/\/grenzinfo.eu\/erw\/wp-content\/uploads\/sites\/7\/2018\/11\/Jaetsch-Daniel.jpg","articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/","url":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/","name":"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt - Rhein-Waal","isPartOf":{"@id":"https:\/\/grenzinfo.eu\/erw\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#primaryimage"},"image":{"@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#primaryimage"},"thumbnailUrl":"https:\/\/grenzinfo.eu\/erw\/wp-content\/uploads\/sites\/7\/2018\/11\/Jaetsch-Daniel.jpg","datePublished":"2018-11-21T13:32:30+00:00","author":{"@id":"https:\/\/grenzinfo.eu\/erw\/#\/schema\/person\/ec7710b37fdb52b8fb42d84b368d705f"},"breadcrumb":{"@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#primaryimage","url":"https:\/\/grenzinfo.eu\/erw\/wp-content\/uploads\/sites\/7\/2018\/11\/Jaetsch-Daniel.jpg","contentUrl":"https:\/\/grenzinfo.eu\/erw\/wp-content\/uploads\/sites\/7\/2018\/11\/Jaetsch-Daniel.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/grenzinfo.eu\/erw\/nl\/business-fruehstueck-zum-thema-grenzueberschreitender-arbeitsmarkt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/grenzinfo.eu\/erw\/"},{"@type":"ListItem","position":2,"name":"Business-Fr\u00fchst\u00fcck zum Thema grenz\u00fcberschreitender Arbeitsmarkt"}]},{"@type":"WebSite","@id":"https:\/\/grenzinfo.eu\/erw\/#website","url":"https:\/\/grenzinfo.eu\/erw\/","name":"Rhein-Waal","description":"Grenzinfopunkt Rhein-Waal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grenzinfo.eu\/erw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/grenzinfo.eu\/erw\/#\/schema\/person\/ec7710b37fdb52b8fb42d84b368d705f","name":"flipse","url":"https:\/\/grenzinfo.eu\/erw\/author\/flipse\/"}]}},"lang":"nl","translations":{"nl":2188},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/posts\/2188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/comments?post=2188"}],"version-history":[{"count":0,"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/posts\/2188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/media\/2189"}],"wp:attachment":[{"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/media?parent=2188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/categories?post=2188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzinfo.eu\/erw\/wp-json\/wp\/v2\/tags?post=2188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}